{"id":11291,"date":"2026-03-30T06:21:46","date_gmt":"2026-03-30T06:21:46","guid":{"rendered":"https:\/\/www.splekawica.pl\/?p=11291"},"modified":"2026-04-01T12:18:52","modified_gmt":"2026-04-01T12:18:52","slug":"turniej-pilki-recznej","status":"publish","type":"post","link":"https:\/\/www.splekawica.pl\/index.php\/2026\/03\/30\/turniej-pilki-recznej\/","title":{"rendered":"Turniej pi\u0142ki r\u0119cznej"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Co to by\u0142a za walka! <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd25\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t50\/1\/16\/1f525.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u26bd\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taf\/1\/16\/26bd.png\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Za nami niesamowite sportowe emocje i ogromne zaanga\u017cowanie naszych uczni\u00f3w <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcaa\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t6c\/1\/16\/1f4aa.png\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W finale m\u0142odsi ch\u0142opcy stoczyli prawdziwy b\u00f3j \u2013 niestety po dogrywce i rzutach karnych musieli uzna\u0107 wy\u017cszo\u015b\u0107 dru\u017cyny ze Stryszowa, ko\u0144cz\u0105c turniej na \u015bwietnym 2. miejscu <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83e\udd48\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t15\/1\/16\/1f948.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc4f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tfe\/1\/16\/1f44f.png\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00f3wnie\u017c nasze dziewczyny spisa\u0142y si\u0119 znakomicie, wywalczaj\u0105c 2. miejsce \u2013 brawo za determinacj\u0119 i ducha walki! <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc99\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t6c\/1\/16\/1f499.png\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Starsi ch\u0142opcy tak\u017ce pokazali klas\u0119, zajmuj\u0105c 3. miejsce <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83e\udd49\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t96\/1\/16\/1f949.png\"><\/p>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-1caf3bda     \"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-2 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"11292\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659877254_1485546849940288_8809450353917427165_n-768x1024.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659877254_1485546849940288_8809450353917427165_n-768x1024.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659877254_1485546849940288_8809450353917427165_n-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"11293\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-768x1024.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-768x1024.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"11294\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/660062455_1485546756606964_1189596176227030585_n-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/660062455_1485546756606964_1189596176227030585_n-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/660062455_1485546756606964_1189596176227030585_n-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"11295\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/660796668_1485546859940287_878143365907556082_n-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/660796668_1485546859940287_878143365907556082_n-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/660796668_1485546859940287_878143365907556082_n-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"11296\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/661003011_1485546773273629_2610848309472853082_n-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/661003011_1485546773273629_2610848309472853082_n-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/661003011_1485546773273629_2610848309472853082_n-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"11297\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/661660547_1485546869940286_2919386534763677728_n-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/661660547_1485546869940286_2919386534763677728_n-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/661660547_1485546869940286_2919386534763677728_n-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__control-lightbox' tabindex='0'>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper spectra-image-gallery__control-lightbox--main\" dir=\"\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659877254_1485546849940288_8809450353917427165_n.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/660062455_1485546756606964_1189596176227030585_n.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/660796668_1485546859940287_878143365907556082_n.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/661003011_1485546773273629_2610848309472853082_n.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/661660547_1485546869940286_2919386534763677728_n.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t<\/div>\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button class='spectra-image-gallery__control-lightbox--close' aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t","protected":false},"excerpt":{"rendered":"<p>Co to by\u0142a za walka! Za nami niesamowite sportowe emocje i ogromne zaanga\u017cowanie naszych uczni\u00f3w W finale m\u0142odsi ch\u0142opcy stoczyli [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-11291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-szkola"],"uagb_featured_image_src":{"full":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n.jpg",1536,2048,false],"thumbnail":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-150x150.jpg",150,150,true],"medium":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-225x300.jpg",225,300,true],"medium_large":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-768x1024.jpg",640,853,true],"large":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-768x1024.jpg",640,853,true],"1536x1536":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-1152x1536.jpg",1152,1536,true],"2048x2048":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n.jpg",1536,2048,false],"bizberg_medium":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-300x300.jpg",300,300,true],"bizberg_gallery":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-500x400.jpg",500,400,true],"bizberg_blog_list":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-368x240.jpg",368,240,true],"bizberg_detail_image":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-825x400.jpg",825,400,true],"bizberg_detail_image_no_sidebar":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-920x400.jpg",920,400,true],"bizberg_portfolio_homepage":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-600x400.jpg",600,400,true],"bizberg_blog_list_no_sidebar_1":["https:\/\/www.splekawica.pl\/wp-content\/uploads\/2026\/04\/659888254_1485546766606963_244439276993218564_n-220x190.jpg",220,190,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.splekawica.pl\/index.php\/author\/admin\/"},"uagb_comment_info":5,"uagb_excerpt":"Co to by\u0142a za walka! Za nami niesamowite sportowe emocje i ogromne zaanga\u017cowanie naszych uczni\u00f3w W finale m\u0142odsi ch\u0142opcy stoczyli [&hellip;]","_links":{"self":[{"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/posts\/11291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/comments?post=11291"}],"version-history":[{"count":1,"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/posts\/11291\/revisions"}],"predecessor-version":[{"id":11298,"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/posts\/11291\/revisions\/11298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/media\/11293"}],"wp:attachment":[{"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/media?parent=11291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/categories?post=11291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.splekawica.pl\/index.php\/wp-json\/wp\/v2\/tags?post=11291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}